{"id":4749,"date":"2013-06-12T14:54:25","date_gmt":"2013-06-12T14:54:25","guid":{"rendered":"https:\/\/enfermeriacanaria.com\/wptfe\/?p=4749"},"modified":"2013-06-12T14:54:25","modified_gmt":"2013-06-12T14:54:25","slug":"felicitacion-a-los-nuevos-doctores-enfermeros-que-han-realizado-hoy-la-defensa-de-su-tesis-doctoral","status":"publish","type":"post","link":"https:\/\/enfermeriacanaria.com\/wptfe\/felicitacion-a-los-nuevos-doctores-enfermeros-que-han-realizado-hoy-la-defensa-de-su-tesis-doctoral\/","title":{"rendered":"Felicitaci\u00f3n a los nuevos Doctores Enfermeros que han realizado hoy la defensa de su tesis doctoral"},"content":{"rendered":"<p>Desde el Colegio de Enfermeros de Santa Cruz de Tenerife, el Presidente y la Junta de Gobierno, queremos felicitar a los nuevos Doctores, los enfermeros Dra. D\u00f1a. Mar\u00eda Noelia Garc\u00eda Hern\u00e1ndez y Dr. D. Carlos Rodr\u00edguez Rocha que, defendieron de manera brillante sus tesis doctorales \u00a0\u00ab<em>Dise\u00f1o, prueba e incorporaci\u00f3n de un sistema estructurado de valoraci\u00f3n en un servicio de urgencias pedi\u00e1trico de Atenci\u00f3n Primaria\u00bb<\/em> y \u00ab<em>La espirometr\u00eda en Atenci\u00f3n Primaria de Tenerife. Utilizaci\u00f3n y calidad<\/em>\u00bb respectivamente. \u00a0Es de destacar la excelente calidad tanto a nivel cient\u00edfico como investigador en ambos trabajos, apoyado por unos directores de tesis de prestigio.<br \/>\nEsto supone un avance para los enfermeros de Tenerife, que al alcanzar el doctorado superan un reto tanto a nivel personal como profesional. El colectivo enfermero en Canarias, alcanza de esta forma, nuevas cotas de excelencia en su labor.<br \/>\nEstamos orgullosos de todos los enfermeros que han logrado este nivel acad\u00e9mico ya que uno de los objetivos de la Organizaci\u00f3n Colegial es potenciar la investigaci\u00f3n de enfermer\u00eda a trav\u00e9s del apoyo\u00a0 directo a las becas de investigaci\u00f3n FUNCIS.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_4750\" aria-describedby=\"caption-attachment-4750\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/enfermeriacanaria.com\/wptfe\/wp-content\/uploads\/defensa-de-tesis.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-4750\" title=\"defensa-de-tesis\" src=\"https:\/\/enfermeriacanaria.com\/wptfe\/wp-content\/uploads\/defensa-de-tesis-300x224.jpg\" alt=\"\" width=\"300\" height=\"224\" srcset=\"https:\/\/enfermeriacanaria.com\/wptfe\/wp-content\/uploads\/defensa-de-tesis-300x224.jpg 300w, https:\/\/enfermeriacanaria.com\/wptfe\/wp-content\/uploads\/defensa-de-tesis-1024x764.jpg 1024w, https:\/\/enfermeriacanaria.com\/wptfe\/wp-content\/uploads\/defensa-de-tesis.jpg 1450w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-4750\" class=\"wp-caption-text\">Los nuevos doctores (centro) junto a directores de tesis y miembros del tribunal<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Desde el Colegio de Enfermeros de Santa Cruz de Tenerife, el Presidente y la Junta de Gobierno, queremos felicitar a los nuevos Doctores, los enfermeros Dra. D\u00f1a. Mar\u00eda Noelia Garc\u00eda Hern\u00e1ndez y Dr. D. Carlos [&#8230;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[238],"class_list":["post-4749","post","type-post","status-publish","format-standard","hentry","category-comunicacion","tag-noticias"],"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p57dxf-1eB","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/enfermeriacanaria.com\/wptfe\/wp-json\/wp\/v2\/posts\/4749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enfermeriacanaria.com\/wptfe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enfermeriacanaria.com\/wptfe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enfermeriacanaria.com\/wptfe\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/enfermeriacanaria.com\/wptfe\/wp-json\/wp\/v2\/comments?post=4749"}],"version-history":[{"count":3,"href":"https:\/\/enfermeriacanaria.com\/wptfe\/wp-json\/wp\/v2\/posts\/4749\/revisions"}],"predecessor-version":[{"id":4753,"href":"https:\/\/enfermeriacanaria.com\/wptfe\/wp-json\/wp\/v2\/posts\/4749\/revisions\/4753"}],"wp:attachment":[{"href":"https:\/\/enfermeriacanaria.com\/wptfe\/wp-json\/wp\/v2\/media?parent=4749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enfermeriacanaria.com\/wptfe\/wp-json\/wp\/v2\/categories?post=4749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enfermeriacanaria.com\/wptfe\/wp-json\/wp\/v2\/tags?post=4749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}